{"id":764,"date":"2016-02-23T10:25:36","date_gmt":"2016-02-23T08:25:36","guid":{"rendered":"http:\/\/www.rotweisskassel.de\/verein\/?p=764"},"modified":"2016-02-24T10:11:10","modified_gmt":"2016-02-24T08:11:10","slug":"tolle-ergebnisse-bei-den-hessischen-meisterschaften-karate","status":"publish","type":"post","link":"https:\/\/www.rotweisskassel.de\/verein\/blog\/2016\/02\/23\/tolle-ergebnisse-bei-den-hessischen-meisterschaften-karate\/","title":{"rendered":"Tolle Ergebnisse bei den Hessischen Meisterschaften Karate"},"content":{"rendered":"<p>Bei den Hessenmeisterschaft der Jugend, Junioren, Leistungsklasse, Masterklasse am 20.02.2016 in Maintal hat unser Verein tolle Ergebnisse eingefahren. Gegen eine starke Konkurrenz wurden viele vordere Pl\u00e4tze erk\u00e4mpft.<\/p>\n<p>Das Team des SV Rot-Wei\u00df Kassel e.V. errang den <strong>ersten Platz<\/strong> im <strong>Kumite<\/strong> Freikampf. Haris Dzigal und Mohammed El-Brolosy jeweils den ersten Platz im einzel in Ihrer jeweiligen Gewichtsklasse.<\/p>\n<p>Im <strong>Kata<\/strong> Formenlauf belegte\u00a0Tymoteusz Tobiasinski den<strong> zweiten Platz.<\/strong><\/p>\n<p>Einen Bericht, alle unsere\u00a0Ergebnisse und Fotos finden sich hier <a href=\"https:\/\/www.rotweisskassel.de\/verein\/karate\/?page_id=748&amp;preview=true\">Hessische Meisterschaften Karate 2016<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-772\" src=\"https:\/\/www.rotweisskassel.de\/verein\/wp-content\/uploads\/2016\/02\/Sieger-DSC_0132_01-1200px-150x150.jpg\" alt=\"Sieger Hessische Karate Meisterschaften 2016\" width=\"150\" height=\"150\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Bei den Hessenmeisterschaft der Jugend, Junioren, Leistungsklasse, Masterklasse am 20.02.2016 in Maintal hat unser Verein tolle Ergebnisse eingefahren. Gegen eine starke Konkurrenz wurden viele vordere <a class=\"mh-excerpt-more\" href=\"https:\/\/www.rotweisskassel.de\/verein\/blog\/2016\/02\/23\/tolle-ergebnisse-bei-den-hessischen-meisterschaften-karate\/\" title=\"Tolle Ergebnisse bei den Hessischen Meisterschaften Karate\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,3,2],"tags":[157,154,162,156,155,160,136,127,103,161,159,102,158],"class_list":["post-764","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-karate","category-verein","tag-haris-dzigal","tag-hessen","tag-hessenmeister","tag-hessische-meisterschaften","tag-hm","tag-junioren","tag-karate","tag-kata","tag-kumite","tag-maintal","tag-masterklasse","tag-meisterschaften","tag-sieg-wettkampf"],"_links":{"self":[{"href":"https:\/\/www.rotweisskassel.de\/verein\/wp-json\/wp\/v2\/posts\/764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rotweisskassel.de\/verein\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rotweisskassel.de\/verein\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rotweisskassel.de\/verein\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rotweisskassel.de\/verein\/wp-json\/wp\/v2\/comments?post=764"}],"version-history":[{"count":6,"href":"https:\/\/www.rotweisskassel.de\/verein\/wp-json\/wp\/v2\/posts\/764\/revisions"}],"predecessor-version":[{"id":773,"href":"https:\/\/www.rotweisskassel.de\/verein\/wp-json\/wp\/v2\/posts\/764\/revisions\/773"}],"wp:attachment":[{"href":"https:\/\/www.rotweisskassel.de\/verein\/wp-json\/wp\/v2\/media?parent=764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rotweisskassel.de\/verein\/wp-json\/wp\/v2\/categories?post=764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rotweisskassel.de\/verein\/wp-json\/wp\/v2\/tags?post=764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}